{"id":27,"count":3,"description":"","link":"https:\/\/www.msgova.com.mx\/es\/categoria-producto\/billcon\/","name":"Billcon","slug":"billcon","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.msgova.com.mx\/es\/wp-json\/wp\/v2\/product_cat\/27"}],"collection":[{"href":"https:\/\/www.msgova.com.mx\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.msgova.com.mx\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.msgova.com.mx\/es\/wp-json\/wp\/v2\/product?product_cat=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}